{"id":7,"date":"2022-02-07T15:51:33","date_gmt":"2022-02-07T15:51:33","guid":{"rendered":"https:\/\/mascasascruilles.cat\/index.php\/cistella\/"},"modified":"2024-07-12T10:48:21","modified_gmt":"2024-07-12T08:48:21","slug":"cistella","status":"publish","type":"page","link":"https:\/\/mascasascruilles.cat\/es\/cistella\/","title":{"rendered":"Cesta"},"content":{"rendered":"<style>.kb-row-layout-id_cce953-2d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_cce953-2d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_cce953-2d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_cce953-2d{background-color:#ffffff;}.kb-row-layout-id_cce953-2d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_cce953-2d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id_cce953-2d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_cce953-2d alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column_395e8a-f1 > .kt-inside-inner-col,.kadence-column_395e8a-f1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_395e8a-f1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_395e8a-f1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_395e8a-f1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_395e8a-f1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_395e8a-f1{position:relative;}@media all and (max-width: 1024px){.kadence-column_395e8a-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_395e8a-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_395e8a-f1\"><div class=\"kt-inside-inner-col\">\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"normal","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-7","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cistella - Mas Casas Cru\u00eflles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mascasascruilles.cat\/es\/cistella\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cistella - Mas Casas Cru\u00eflles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mascasascruilles.cat\/es\/cistella\/\" \/>\n<meta property=\"og:site_name\" content=\"Mas Casas Cru\u00eflles\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-12T08:48:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mascasascruilles.cat\\\/cistella\\\/\",\"url\":\"https:\\\/\\\/mascasascruilles.cat\\\/cistella\\\/\",\"name\":\"Cistella - Mas Casas Cru\u00eflles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mascasascruilles.cat\\\/#website\"},\"datePublished\":\"2022-02-07T15:51:33+00:00\",\"dateModified\":\"2024-07-12T08:48:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mascasascruilles.cat\\\/cistella\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mascasascruilles.cat\\\/cistella\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mascasascruilles.cat\\\/cistella\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/mascasascruilles.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cistella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mascasascruilles.cat\\\/#website\",\"url\":\"https:\\\/\\\/mascasascruilles.cat\\\/\",\"name\":\"Mas Casas Cru\u00eflles\",\"description\":\"Granja familiar amb ovelles a Empord\u00e0\",\"publisher\":{\"@id\":\"https:\\\/\\\/mascasascruilles.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mascasascruilles.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mascasascruilles.cat\\\/#organization\",\"name\":\"Mas Casas Cru\u00eflles\",\"url\":\"https:\\\/\\\/mascasascruilles.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mascasascruilles.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mascasascruilles.cat\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-logo_mascasas_negre.jpg\",\"contentUrl\":\"https:\\\/\\\/mascasascruilles.cat\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-logo_mascasas_negre.jpg\",\"width\":756,\"height\":756,\"caption\":\"Mas Casas Cru\u00eflles\"},\"image\":{\"@id\":\"https:\\\/\\\/mascasascruilles.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cistella - Mas Casas Cru\u00eflles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mascasascruilles.cat\/es\/cistella\/","og_locale":"es_ES","og_type":"article","og_title":"Cistella - Mas Casas Cru\u00eflles","og_url":"https:\/\/mascasascruilles.cat\/es\/cistella\/","og_site_name":"Mas Casas Cru\u00eflles","article_modified_time":"2024-07-12T08:48:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mascasascruilles.cat\/cistella\/","url":"https:\/\/mascasascruilles.cat\/cistella\/","name":"Cistella - Mas Casas Cru\u00eflles","isPartOf":{"@id":"https:\/\/mascasascruilles.cat\/#website"},"datePublished":"2022-02-07T15:51:33+00:00","dateModified":"2024-07-12T08:48:21+00:00","breadcrumb":{"@id":"https:\/\/mascasascruilles.cat\/cistella\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mascasascruilles.cat\/cistella\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mascasascruilles.cat\/cistella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/mascasascruilles.cat\/"},{"@type":"ListItem","position":2,"name":"Cistella"}]},{"@type":"WebSite","@id":"https:\/\/mascasascruilles.cat\/#website","url":"https:\/\/mascasascruilles.cat\/","name":"Mas Casas Cru\u00eflles","description":"Granja familiar con ovejas en Empord\u00e0","publisher":{"@id":"https:\/\/mascasascruilles.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mascasascruilles.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mascasascruilles.cat\/#organization","name":"Mas Casas Cru\u00eflles","url":"https:\/\/mascasascruilles.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mascasascruilles.cat\/#\/schema\/logo\/image\/","url":"https:\/\/mascasascruilles.cat\/wp-content\/uploads\/2022\/02\/cropped-logo_mascasas_negre.jpg","contentUrl":"https:\/\/mascasascruilles.cat\/wp-content\/uploads\/2022\/02\/cropped-logo_mascasas_negre.jpg","width":756,"height":756,"caption":"Mas Casas Cru\u00eflles"},"image":{"@id":"https:\/\/mascasascruilles.cat\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"mascasascruilles","author_link":"https:\/\/mascasascruilles.cat\/es\/author\/mascasascruilles\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/mascasascruilles.cat\/es\/wp-json\/wp\/v2\/pages\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mascasascruilles.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mascasascruilles.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mascasascruilles.cat\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mascasascruilles.cat\/es\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":1,"href":"https:\/\/mascasascruilles.cat\/es\/wp-json\/wp\/v2\/pages\/7\/revisions"}],"predecessor-version":[{"id":3554,"href":"https:\/\/mascasascruilles.cat\/es\/wp-json\/wp\/v2\/pages\/7\/revisions\/3554"}],"wp:attachment":[{"href":"https:\/\/mascasascruilles.cat\/es\/wp-json\/wp\/v2\/media?parent=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}